{"id":467,"date":"2022-02-17T01:13:07","date_gmt":"2022-02-17T06:13:07","guid":{"rendered":"https:\/\/www.smartsamerica.com\/?post_type=calculators&#038;p=467"},"modified":"2022-02-17T01:13:07","modified_gmt":"2022-02-17T06:13:07","slug":"should-i-rent-or-buy-a-home","status":"publish","type":"calculators","link":"https:\/\/www.smartsamerica.com\/es\/calculators\/should-i-rent-or-buy-a-home\/","title":{"rendered":"Debo Alquilar O Comprar Una Casa?"},"content":{"rendered":"<p><!--\n\t<script type='text\/javascript' src='https:\/\/ajax.googleapis.com\/ajax\/libs\/jquery\/2.2.1\/jquery.min.js' type='text\/javascript'><\/script>\n\t<script type='text\/javascript' src='https:\/\/www.calcxml.com\/scripts\/tipped\/comboTipped.js' type='text\/javascript'><\/script>\n\t<script type='text\/javascript' src='https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/jquery-ajaxtransport-xdomainrequest\/1.0.2\/jquery.xdomainrequest.min.js'><\/script>\n\t<link href=\"https:\/\/www.calcxml.com\/images\/galleries\/style\/css\/calc-xml-481.css\" rel=\"stylesheet\">\n\/\/--><\/p>\n<p><script type='text\/javascript' src='https:\/\/www.calcxml.com\/scripts\/loadCalc.js?calcTarget=hom06&#038;embed=2&#038;skn=481'><\/script><\/p>\n<div id='calc'><\/div>","protected":false},"excerpt":{"rendered":"<p>Con las tasas de inter\u00e9s cerca de 40 a\u00f1os m\u00ednimo, la decisi\u00f3n de alquilar frente a comprar se vuelve dif\u00edcil.<\/p>","protected":false},"featured_media":0,"template":"","meta":{"content-type":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"category-calculators":[13],"class_list":["post-467","calculators","type-calculators","status-publish","hentry","category-calculators-home-and-mortgage"],"_links":{"self":[{"href":"https:\/\/www.smartsamerica.com\/es\/wp-json\/wp\/v2\/calculators\/467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smartsamerica.com\/es\/wp-json\/wp\/v2\/calculators"}],"about":[{"href":"https:\/\/www.smartsamerica.com\/es\/wp-json\/wp\/v2\/types\/calculators"}],"wp:attachment":[{"href":"https:\/\/www.smartsamerica.com\/es\/wp-json\/wp\/v2\/media?parent=467"}],"wp:term":[{"taxonomy":"category-calculators","embeddable":true,"href":"https:\/\/www.smartsamerica.com\/es\/wp-json\/wp\/v2\/category-calculators?post=467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}