{"id":402,"date":"2022-02-17T00:21:20","date_gmt":"2022-02-17T05:21:20","guid":{"rendered":"https:\/\/www.smartsamerica.com\/?post_type=calculators&#038;p=402"},"modified":"2022-02-17T00:21:20","modified_gmt":"2022-02-17T05:21:20","slug":"feasibility-of-student-loan-repayment","status":"publish","type":"calculators","link":"https:\/\/www.smartsamerica.com\/es\/calculators\/feasibility-of-student-loan-repayment\/","title":{"rendered":"La Viabilidad De Pago De Pr\u00e9stamos De Estudiante"},"content":{"rendered":"<p><!--\n\t<script type='text\/javascript' src='https:\/\/ajax.googleapis.com\/ajax\/libs\/jquery\/2.2.1\/jquery.min.js' type='text\/javascript'><\/script>\n\t<script type='text\/javascript' src='https:\/\/www.calcxml.com\/scripts\/tipped\/comboTipped.js' type='text\/javascript'><\/script>\n\t<script type='text\/javascript' src='https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/jquery-ajaxtransport-xdomainrequest\/1.0.2\/jquery.xdomainrequest.min.js'><\/script>\n\t<link href=\"https:\/\/www.calcxml.com\/images\/galleries\/style\/css\/calc-xml-481.css\" rel=\"stylesheet\">\n\/\/--><\/p>\n<p><script type='text\/javascript' src='https:\/\/www.calcxml.com\/scripts\/loadCalc.js?calcTarget=col02&#038;embed=2&#038;skn=481'><\/script><\/p>\n<div id='calc'><\/div>","protected":false},"excerpt":{"rendered":"<p>Cuando usted pide prestado dinero para la universidad no podr\u00eda estar pensando acerca de su capacidad para pagar el pr\u00e9stamo una vez que te grad\u00faas. Estudiante sobresaliente y los saldos de pr\u00e9stamos puede violar su capacidad para calificar para una casa, auto y otros pr\u00e9stamos personales.<\/p>","protected":false},"featured_media":0,"template":"","meta":{"content-type":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"category-calculators":[11],"class_list":["post-402","calculators","type-calculators","status-publish","hentry","category-calculators-college"],"_links":{"self":[{"href":"https:\/\/www.smartsamerica.com\/es\/wp-json\/wp\/v2\/calculators\/402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smartsamerica.com\/es\/wp-json\/wp\/v2\/calculators"}],"about":[{"href":"https:\/\/www.smartsamerica.com\/es\/wp-json\/wp\/v2\/types\/calculators"}],"wp:attachment":[{"href":"https:\/\/www.smartsamerica.com\/es\/wp-json\/wp\/v2\/media?parent=402"}],"wp:term":[{"taxonomy":"category-calculators","embeddable":true,"href":"https:\/\/www.smartsamerica.com\/es\/wp-json\/wp\/v2\/category-calculators?post=402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}